<br />
<b>Deprecated</b>:  strcasecmp(): Passing null to parameter #1 ($string1) of type string is deprecated in <b>/home/espiritazz/www/wp-content/plugins/ads-wp-site-count/ads_wpsitecount.php</b> on line <b>513</b><br />
{"id":1364,"date":"2023-12-09T12:33:20","date_gmt":"2023-12-09T11:33:20","guid":{"rendered":"https:\/\/www.espiritasmadrid.com\/?p=1364"},"modified":"2023-12-09T12:33:20","modified_gmt":"2023-12-09T11:33:20","slug":"no-soy-feliz-3","status":"publish","type":"post","link":"https:\/\/www.espiritasmadrid.com\/index.php\/2023\/12\/09\/no-soy-feliz-3\/","title":{"rendered":"\u00a1No soy feliz!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Art\u00edculo redactado por Juan Miguel Fern\u00e1ndez<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A lo largo de nuestras vidas habremos escuchado esta expresi\u00f3n repetidas veces, no solamente a personas que por su angustiosa situaci\u00f3n se podr\u00eda considerar justificable, sino a otras muchas que gozan aparentemente de todo lo que ambicionaron en este mundo: riqueza, poder, posici\u00f3n, popularidad, etc. Y quiz\u00e1 alguno de los que les observan se preguntan \u00bfQu\u00e9 le falta para ser feliz si posee \u201ctodo?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La <em><strong>Doctrina de los Esp\u00edritus <\/strong><\/em>a trav\u00e9s del estudio, nos ense\u00f1a que cuantos estamos encarnados en este planeta vivimos dominados fundamentalmente por el dolor y el sufrimiento debido al estado evolutivo en el que nos encontramos. Record\u00e1ndonos as\u00ed que la Tierra es un \u201cmundo de expiaciones y pruebas\u201d donde debemos progresar espiritualmente con el esfuerzo, ante la necesidad del libre desenvolvimiento individual. Siendo la libertad moral proporcional al estado de avance del ser, colaborando asimismo en el mejoramiento general de la Humanidad, que nos llevar\u00e1 a la felicidad universal como resultado definitivo de la evoluci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La gran mayor\u00eda de aquellas personas que disfrutan de \u201ctodo\u201d, pero que sienten persistentemente el vacio interior, ni siquiera se plantearon la necesidad de adquirir, para a\u00f1adir a su amplio abanico de propiedades, la riqueza m\u00e1s natural y gratuita: la grandeza espiritual. Lucharon durante a\u00f1os para conquistar aquello que era tangible y tocaban con las manos, lo que pod\u00edan mostrar a amigos y enemigos, engordando su orgullo y vanidad, olvidando que la felicidad no consiste en atesorar bienes materiales aqu\u00ed en la Tierra. Bienes conquistados que no se podr\u00e1n llevar al otro lado de la vida f\u00edsica, ignorando que el \u00fanico equipaje que les acompa\u00f1ar\u00e1 ser\u00e1n las virtudes y las imperfecciones que acumularon en su encarnaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>El evangelio seg\u00fan el Espiritismo, Cap\u00edtulo XXV, Item. 6 <\/strong><\/em>ya nos alerta al respecto: <em>\u201cNo amonton\u00e9is tesoros en la Tierra, donde el or\u00edn y los gusanos los consume, donde los ladrones los desentierran y roban; m\u00e1s amontonad tesoros en el cielo, donde ni el or\u00edn ni los gusanos los consumen, porque donde est\u00e1 vuestro tesoro, all\u00ed est\u00e1 tambi\u00e9n vuestro coraz\u00f3n\u201d.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cierto es que la riqueza es una de las pruebas m\u00e1s dif\u00edciles de superar. Ella nos predispone a cometer acciones que nos apartan del camino id\u00f3neo, pero recordemos tambi\u00e9n que gracias a ella, utiliz\u00e1ndola debidamente, se puede adquirir el bagaje moral que nos har\u00e1 el regreso a la Patria Espiritual mucho m\u00e1s apacible.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si todos los que sienten la frase que encabeza estas l\u00edneas dedicasen tan solo unos instantes de su tiempo para meditar sobre esta situaci\u00f3n, elevando el pensamiento a lo Alto buscando respuestas, estamos seguros que las encontrar\u00edan. Nuestros amigos los Esp\u00edritus, observ\u00e1ndonos con esperanza, se encuentran siempre dispuestos a colaborar en el bien. Ellos tienen el compromiso de inspirarnos, intuirnos y encaminarnos apart\u00e1ndonos del entorno materialista que nos domina y que nos tiene sumergidos en le negatividad. Tan solo esperan nuestra llamada para acudir a nuestro lado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Art\u00edculo redactado por Juan Miguel Fern\u00e1ndez A lo largo de nuestras vidas habremos escuchado esta expresi\u00f3n repetidas veces, no solamente a personas que por su angustiosa situaci\u00f3n se podr\u00eda considerar justificable, sino a otras muchas que gozan aparentemente de todo lo que ambicionaron en este mundo: riqueza, poder, posici\u00f3n, popularidad, etc. Y quiz\u00e1 alguno de&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1364","post","type-post","status-publish","format-standard","hentry","category-articulo"],"_links":{"self":[{"href":"https:\/\/www.espiritasmadrid.com\/index.php\/wp-json\/wp\/v2\/posts\/1364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.espiritasmadrid.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.espiritasmadrid.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.espiritasmadrid.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.espiritasmadrid.com\/index.php\/wp-json\/wp\/v2\/comments?post=1364"}],"version-history":[{"count":1,"href":"https:\/\/www.espiritasmadrid.com\/index.php\/wp-json\/wp\/v2\/posts\/1364\/revisions"}],"predecessor-version":[{"id":1365,"href":"https:\/\/www.espiritasmadrid.com\/index.php\/wp-json\/wp\/v2\/posts\/1364\/revisions\/1365"}],"wp:attachment":[{"href":"https:\/\/www.espiritasmadrid.com\/index.php\/wp-json\/wp\/v2\/media?parent=1364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.espiritasmadrid.com\/index.php\/wp-json\/wp\/v2\/categories?post=1364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.espiritasmadrid.com\/index.php\/wp-json\/wp\/v2\/tags?post=1364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}