<br />
<b>Deprecated</b>:  strcasecmp(): Passing null to parameter #1 ($string1) of type string is deprecated in <b>/home/espiritazz/www/wp-content/plugins/ads-wp-site-count/ads_wpsitecount.php</b> on line <b>513</b><br />
{"id":1245,"date":"2023-10-07T13:37:36","date_gmt":"2023-10-07T11:37:36","guid":{"rendered":"https:\/\/www.espiritasmadrid.com\/?p=1245"},"modified":"2023-10-07T13:41:14","modified_gmt":"2023-10-07T11:41:14","slug":"convivir-es-decer","status":"publish","type":"post","link":"https:\/\/www.espiritasmadrid.com\/index.php\/2023\/10\/07\/convivir-es-decer\/","title":{"rendered":"Convivir es ceder"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Art\u00edculo redactado por Juan Miguel Fern\u00e1ndez Mu\u00f1oz<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aquellos que por nuestra naturaleza somos observadores, apreciamos en las diversas situaciones que atraviesan nuestra vida, m\u00faltiples ocasiones que nos invitan a la reflexi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hace d\u00edas advert\u00edamos, al viajar en un medio de transporte de nuestra ciudad, c\u00f3mo al llegar al punto de destino las personas se agrupaban en la puerta de salida para descender del vag\u00f3n del metro. En el and\u00e9n de la estaci\u00f3n los individuos que esperaban y que se preparaban a su vez para penetrar en el vag\u00f3n, lo imped\u00edan de tal manera que no era posible hacerse camino, si no era a base de empujones para poder salir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este incidente, que es considerado como habitual, se repite continuamente dando lugar a roces, enfrentamientos y malos modos de los viajeros que se desplazan en los transportes p\u00fablicos de las grandes ciudades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las personas que viven de espaldas a la convivencia desconocen que pertenecen a un conjunto arm\u00f3nico donde, apoy\u00e1ndonos los unos en los otros, todos somos necesarios para nuestra propia evoluci\u00f3n, y marchan ignorantes por la vida absortos en sus pensamientos sin considerar los derechos de los dem\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue Gandhi quien se\u00f1al\u00f3: \u201cOJO POR OJO Y EL MUNDO QUEDAR\u00c1 CIEGO\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a><\/a> La tolerancia y la paciencia son virtudes que el ser humano debe cultivar porque fortalecen la humildad, al tiempo que nos hacen comprender la necesidad del mejoramiento \u00edntimo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No se trata de ceder a las exigencias caprichosas que nos deparan, pero s\u00ed de analizar a d\u00f3nde nos conduce nuestra obstinaci\u00f3n y que caminos se nos abren con nuestra flexibilidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Actuando as\u00ed, nuestro car\u00e1cter se dulcificar\u00e1 al asimilar el Esp\u00edritu con m\u00e1s facilidad las buenas acciones. Mientras que aquellas otras que nuestra conciencia recoge, servir\u00e1n para perturbarnos debido a los errores cometidos y a la terquedad de nuestras malas decisiones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dif\u00edcil es convivir, esa es la gran prueba que debemos superar entre unos y otros. Mientras no despertemos a la fraternidad y pensemos ego\u00edstamente en nosotros, permaneceremos anclados sin progreso espiritual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cedamos para recibir y as\u00ed podremos abrir caminos a la tolerancia y al amor, sin ninguna necesidad de ser infelices.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Siempre hay tiempo para restaurar y corregir, comenzar y recomenzar. No se detenga, act\u00fae, mejore, bendiga la vida y ella le har\u00e1 feliz.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Art\u00edculo redactado por Juan Miguel Fern\u00e1ndez Mu\u00f1oz Aquellos que por nuestra naturaleza somos observadores, apreciamos en las diversas situaciones que atraviesan nuestra vida, m\u00faltiples ocasiones que nos invitan a la reflexi\u00f3n. Hace d\u00edas advert\u00edamos, al viajar en un medio de transporte de nuestra ciudad, c\u00f3mo al llegar al punto de destino las personas se agrupaban&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1245","post","type-post","status-publish","format-standard","hentry","category-articulo"],"_links":{"self":[{"href":"https:\/\/www.espiritasmadrid.com\/index.php\/wp-json\/wp\/v2\/posts\/1245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.espiritasmadrid.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.espiritasmadrid.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.espiritasmadrid.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.espiritasmadrid.com\/index.php\/wp-json\/wp\/v2\/comments?post=1245"}],"version-history":[{"count":2,"href":"https:\/\/www.espiritasmadrid.com\/index.php\/wp-json\/wp\/v2\/posts\/1245\/revisions"}],"predecessor-version":[{"id":1247,"href":"https:\/\/www.espiritasmadrid.com\/index.php\/wp-json\/wp\/v2\/posts\/1245\/revisions\/1247"}],"wp:attachment":[{"href":"https:\/\/www.espiritasmadrid.com\/index.php\/wp-json\/wp\/v2\/media?parent=1245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.espiritasmadrid.com\/index.php\/wp-json\/wp\/v2\/categories?post=1245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.espiritasmadrid.com\/index.php\/wp-json\/wp\/v2\/tags?post=1245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}